{"id":10758,"date":"2019-09-21T23:10:18","date_gmt":"2019-09-21T21:10:18","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=10758"},"modified":"2020-06-08T20:19:48","modified_gmt":"2020-06-08T18:19:48","slug":"tecco-photo-dsg260-duo-semigloss","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2019\/09\/tecco-photo-dsg260-duo-semigloss\/","title":{"rendered":"TECCO PHOTO DSG260 DUO Semigloss"},"content":{"rendered":"<p><span class=\"normal\">Este papel de doble cara est\u00e1 recubierto de polietileno con superficie brillante y sedoso es el producto ideal para crear \u00e1lbumes de fotos profesional y calendarios. Se destaca por su amplia gama de colores y luminosidad incre\u00edble.<\/span><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/tecco\/i\/foto_DS275_duo_satin_400.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este papel de doble cara est\u00e1 recubierto de polietileno con superficie brillante y sedoso es el producto ideal para crear \u00e1lbumes de fotos profesional y calendarios. Se destaca por su amplia gama de colores y luminosidad incre\u00edble.<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[1],"tags":[24906,22130,16512,16513,24666],"class_list":["post-10758","post","type-post","status-publish","format-standard","hentry","category-general","tag-composicion-papel-impresora-fotografico","tag-comprar-papel-impresion-fotografica-offset","tag-mejor-precio-papel-satinado-doble-cara-120-gr-m2","tag-papel-doble-cara-fotografico-120-gr-m2","tag-papel-fotografico-a3-dos-caras-injet"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=10758"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/10758\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=10758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=10758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=10758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}