{"id":1360,"date":"2010-08-18T11:25:38","date_gmt":"2010-08-18T09:25:38","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=1360"},"modified":"2024-09-23T09:47:27","modified_gmt":"2024-09-23T07:47:27","slug":"calibracion-con-sypder-cube","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2010\/08\/calibracion-con-sypder-cube\/","title":{"rendered":"Calibraci\u00f3n con Sypder Cube"},"content":{"rendered":"<div align=\"left\"><span class=\"h3\">Un simple tutorial de como utilizar el Spyder Cube<\/span><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/www.microgamma.com\/datacolor\/cube\/L1000375_500.jpg\" alt=\"Cube colocado para que aparezca en la fotograf\u00eda\" width=\"500\" height=\"751\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.microgamma.com\/datacolor\/cube\/L1000369_500.jpg\" alt=\"ha de colocarse con la cara inferior que contiene la trampa negra orientada hacia adelante, con las dos caras blancas y grises visibles\" width=\"500\" height=\"333\" \/><\/p>\n<p class=\"normal\">Colocamos el cube en la escena donde realizaremos la fotograf\u00eda, en las mismas condiciones lum\u00ednicas en que realizaremos la fotograf\u00eda.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.microgamma.com\/datacolor\/tonturial\/tonturial_03.jpg\" alt=\"SpyderCube en Capture One\" width=\"630\" height=\"797\" \/><\/p>\n<p class=\"normal\">Los pasos son los mismos sea cual sea el software utilizado,, a continuaci\u00f3n mostramos distintas capturas realizadas en Capture One.<\/p>\n<p class=\"normal\">En el primer paso buscamos la temperatura, con la herramienta \u00abequilibrio de blancos\u00bb o de grises, seg\u00fan el programa. Marcamos la zona del gris del 18%. Procedemos a posteriori a un retoque detallado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.microgamma.com\/datacolor\/tonturial\/tonturial_01.jpg\" alt=\"SpyderCube en Capture One\" width=\"630\" height=\"797\" \/><\/p>\n<p class=\"normal\">En el siguiente paso medimos la bola de cromo en que tendremos una zona blanca quemada y una zona negra en la parte inferior de negro absoluto. Ajustamos la exposici\u00f3n de los canales para que no se recorten en el histograma.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.microgamma.com\/datacolor\/tonturial\/tonturial_04.jpg\" alt=\"histograma\" width=\"337\" height=\"160\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.microgamma.com\/datacolor\/tonturial\/tonturial_02.jpg\" alt=\"SpyderCube en Capture One\" width=\"630\" height=\"797\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"normal\">Ya tenemos la medici\u00f3n y los par\u00e1metros en un programa como Capture One solo los tiene que copiar y aplicar a la fotograf\u00eda o serie.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.microgamma.com\/datacolor\/tonturial\/tonturial_05.jpg\" alt=\"aplicaci\u00f3n de cambios\" width=\"337\" height=\"160\" \/><\/p>\n<p class=\"detall-centre\"><a href=\"http:\/\/www.shutterstock.com\/pic.mhtml?id=59212516\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.microgamma.com\/datacolor\/cube\/stock-photo-colored-pencils-in-a-jar-59212516.jpg\" alt=\"Fotograf\u00eda corregida\" width=\"300\" height=\"470\" border=\"0\" \/><\/a><\/p>\n<p class=\"detall-centre\"><a class=\"detall-centre\" href=\"http:\/\/www.shutterstock.com\/pic.mhtml?id=59212516\">http:\/\/www.shutterstock.com\/pic.mhtml?id=59212516<\/a><\/p>\n<p><span class=\"normal\">Y este es el resultado: una vez pasada la fotograf\u00eda por Photoshop esta est\u00e1 lista para su venta. Una vez tenemos los valores de correcci\u00f3n podemos aplicarlos a otras im\u00e1genes tomadas bajo las mismas condiciones.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un simple tutorial de como utilizar el Spyder Cube Colocamos el cube en la escena donde realizaremos la fotograf\u00eda, en las mismas condiciones lum\u00ednicas en que realizaremos la fotograf\u00eda. &nbsp; Los pasos son los mismos sea cual sea el software utilizado,, a continuaci\u00f3n mostramos distintas capturas realizadas en Capture One. En el primer paso buscamos [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[8,364],"tags":[29238,2305,555,21240,557,5006,556],"class_list":["post-1360","post","type-post","status-publish","format-standard","hentry","category-calibradores-para-monitor","category-datacolor-calibradores-para-monitor","tag-calibracion-camara","tag-calibracion-camara-digital","tag-dacolor","tag-que-es-spyder-cube","tag-spyder-cube","tag-spyder-cube-online-course","tag-spydercube"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=1360"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/1360\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=1360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=1360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=1360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}