{"id":3329,"date":"2012-11-26T14:37:53","date_gmt":"2012-11-26T12:37:53","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=3329"},"modified":"2012-12-24T13:11:06","modified_gmt":"2012-12-24T11:11:06","slug":"carl-zeiss-50-mm-zm","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2012\/11\/carl-zeiss-50-mm-zm\/","title":{"rendered":"Carl Zeiss 50 mm zm"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"zeiss sonnar 1,5 50\" alt=\"\" src=\"http:\/\/www.microgamma.com\/zeiss\/zeiss_zm\/C_sonnar_50\/L1380560_600.jpg\" width=\"500\" height=\"333\" \/><\/p>\n<p>Esta longitud focal est\u00e1ndar ofrece las calidades especiales que lo hacen ideal para el retrato.<\/p>\n<p>El C Sonnar T* 1,5\/50 mm es una lente muy especial basado en un dise\u00f1o de 1930 de la propia Zeiss. Es el competidor directo del Summilux de Leica, con una ligera diferencia en la apertura pero con un dise\u00f1o similar, pero sin lentes esf\u00e9ricas que reducir\u00edan su bokeh caracter\u00edstico. Es de gran ayuda para conseguir fotos con un toque art\u00edstico, para aislar a un sujeto del fondo en fotograf\u00eda social o callejera. A f2,8 el objetivo se empieza a desarrollar como un objetivo mas convencional y entre f4 y 5,6 pude utilizarse en documentaci\u00f3n o fotograf\u00eda t\u00e9cnica. Su estructura \u00abC\u00bb compacta lo hacen un 25% mas ligero que su competidor con la misma luminosidad<\/p>\n<p>Aplicaciones: foto-periodismo, retrato.<\/p>\n<p><a href=\"http:\/\/www.microgamma.es\/blog\/wp-content\/uploads\/MG_6357_600.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-3332\" title=\"_MG_6357_600\" alt=\"objetivo zeiss\" src=\"http:\/\/www.microgamma.es\/blog\/wp-content\/uploads\/MG_6357_600.jpg\" width=\"370\" height=\"370\" srcset=\"https:\/\/www.microgamma.es\/blog\/wp-content\/uploads\/MG_6357_600.jpg 500w, https:\/\/www.microgamma.es\/blog\/wp-content\/uploads\/MG_6357_600-150x150.jpg 150w, https:\/\/www.microgamma.es\/blog\/wp-content\/uploads\/MG_6357_600-300x300.jpg 300w\" sizes=\"auto, (max-width: 370px) 100vw, 370px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"\" src=\"http:\/\/www.microgamma.com\/zeiss\/zeiss_zm\/C_sonnar_50\/CSonnar_1_630.png\" width=\"490\" height=\"574\" \/><\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/zeiss\/c_sonnar_50_1_5.php\">http:\/\/www.microgamma.com\/zeiss\/c_sonnar_50_1_5.php<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta longitud focal est\u00e1ndar ofrece las calidades especiales que lo hacen ideal para el retrato. El C Sonnar T* 1,5\/50 mm es una lente muy especial basado en un dise\u00f1o de 1930 de la propia Zeiss. Es el competidor directo del Summilux de Leica, con una ligera diferencia en la apertura pero con un dise\u00f1o [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[355],"tags":[611,704,705,565,412,613],"class_list":["post-3329","post","type-post","status-publish","format-standard","hentry","category-zeiss","tag-carl-zeiss-zm","tag-lentes-montura-m","tag-objetivos-montura-m","tag-objetivos-para-leica-m9","tag-objetivos-zeiss","tag-zeiss-sonnar"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3329"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3329\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}