{"id":3454,"date":"2012-07-11T18:00:05","date_gmt":"2012-07-11T16:00:05","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=3454"},"modified":"2015-08-20T09:30:16","modified_gmt":"2015-08-20T07:30:16","slug":"limpiar-sensor-canon-5d-mark-ii","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2012\/07\/limpiar-sensor-canon-5d-mark-ii\/","title":{"rendered":"limpiar sensor canon 5d mark II"},"content":{"rendered":"<p>La Canon 5D MarkII y Mark III son c\u00e1maras de formato completo, full frame, por lo que requieren de <a href=\"http:\/\/www.microgamma.com\/photosol\/sensor_swab_3.php\">Sensor SWAB de tipo 3<\/a> para su limpieza:<\/p>\n<p>Una soluci\u00f3n simple es el Kit 3 de Photosol, con el m\u00ednimo imprescindible para la limpieza de la c\u00e1mara<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/photosol\/kit_basico_3.php\">http:\/\/www.microgamma.com\/photosol\/kit_basico_3.php<\/a><\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/photosol\/kit_basico_3.php\"><img loading=\"lazy\" decoding=\"async\" title=\"limpiar canon 5d\" src=\"http:\/\/www.microgamma.com\/photosol\/i\/survivalkit_basic_1838_detail_630.jpg\" alt=\"\" width=\"434\" height=\"251\" \/><\/a><\/p>\n<p class=\"normal_instop\">El pack contiene:<\/p>\n<ul class=\"normal_instop\">\n<li><span class=\"titol_1\"><strong>4 sensor Swabs TIPO 3<\/strong> (envasados herm\u00e9ticamente)<\/span><\/li>\n<li>10 PEC*PADs<\/li>\n<li>1 paquete e-wipe<\/li>\n<li>1 eclipse (0.5oz, aprox.14.2ml)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"sensor swab\" src=\"http:\/\/www.microgamma.com\/225\/sensor_swab_bastonet_tipus3.jpg\" alt=\"\" width=\"160\" height=\"160\" \/><\/p>\n<p>Los Sensor Swab se venden de forma individual<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/photosol\/sensor_swab3_individual.php\">http:\/\/www.microgamma.com\/photosol\/sensor_swab3_individual.php<\/a><\/p>\n<p>En cajas de 12 unidades<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/photosol\/sensor_swab_3.php\">http:\/\/www.microgamma.com\/photosol\/sensor_swab_3.php<\/a><\/p>\n<p>O en formato individual impregnado de liquido Eclipse, una soluci\u00f3n muy practica.<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/photosol\/sensor_swab_plus3_sol.php\">http:\/\/www.microgamma.com\/photosol\/sensor_swab_plus3_sol.php<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>De otros fabricantes como Green Clean esta disponible un kit de dos Swabs uno h\u00famedo y el otro seco para una limpieza integral<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/green_clean\/sc-4060-1.php\"><img decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.microgamma.com\/green_clean\/4060_3\/green225.jpg\" alt=\"\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/green_clean\/sc-4060-1.php\">http:\/\/www.microgamma.com\/green_clean\/sc-4060-1.php<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Tambi\u00e9n de Photosol esta disponible del Kit tres en versi\u00f3n profesional<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/photosol\/kit_profesional_3.php\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.microgamma.com\/photosol\/i\/kit_de_limpieza_profesional.jpg\" alt=\"\" width=\"401\" height=\"306\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Para una limpieza en la que la suciedad sea provocada por polvo en suspensi\u00f3n es recomendable el uso de un pincel como el VisibleDust Arctic Butterfly 724<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/visible_dust\/visibledust_arctic_butterfly_724.php\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" title=\"visibledust\" src=\"http:\/\/www.microgamma.com\/visible_dust\/724\/Blue_Ab_500X500_new.jpg\" alt=\"\" width=\"349\" height=\"349\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>VisibleDust tambi\u00e9n dispone de unos kits de limpieza, que var\u00edan en funci\u00f3n del grado de suciedad, se trata de dos tipos de Sensor Swab y de tres l\u00edquidos. En el caso de las Canon 5D MKII y MKIII no hay pr\u00e1cticamente casos de manchas de aceite, por lo que el Sensor Clean o el VDust Plus son perfectamente validos.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/visible_dust\/liquidos_visibledust.php\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.microgamma.com\/visible_dust\/i\/liquids.jpg\" alt=\"\" width=\"525\" height=\"184\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Canon 5D MarkII y Mark III son c\u00e1maras de formato completo, full frame, por lo que requieren de Sensor SWAB de tipo 3 para su limpieza: Una soluci\u00f3n simple es el Kit 3 de Photosol, con el m\u00ednimo imprescindible para la limpieza de la c\u00e1mara http:\/\/www.microgamma.com\/photosol\/kit_basico_3.php El pack contiene: 4 sensor Swabs TIPO 3 [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[584],"tags":[657,647,1537,654,1536,523,655,656,732,428,427],"class_list":["post-3454","post","type-post","status-publish","format-standard","hentry","category-limpieza-sensor-y-camara","tag-limpiar-canon-5d","tag-limpiar-sensor","tag-limpiar-sensor-canon-5d","tag-limpiar-sensor-canon-5d-mark-ii","tag-limpiar-sensor-canon-5d-mark-iii","tag-liquido-eclipse","tag-netejar-camera-5d","tag-netejar-sensor-full-frame","tag-nuevos-productos-para-limpieza-camaras","tag-photosol-2","tag-sensor-swab"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=3454"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/3454\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=3454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=3454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=3454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}