{"id":4151,"date":"2013-04-16T18:31:21","date_gmt":"2013-04-16T16:31:21","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=4151"},"modified":"2013-04-16T22:01:44","modified_gmt":"2013-04-16T20:01:44","slug":"nuevo-colornavigator","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2013\/04\/nuevo-colornavigator\/","title":{"rendered":"Nuevo ColorNavigator"},"content":{"rendered":"<p>Se ha producido una actualizaci\u00f3n del software ColorNavigator 6.4.2.11 que es importante aplicar. A parte de cambios menores como es la compatibilidad de nuevos monitores hay que destacar la compatibilidad del calibrador <a href=\"http:\/\/www.microgamma.com\/basiccolor\/basICColor_DISCUS.php\">Basiccolor Discus<\/a><\/p>\n<p>Se han realizado cambios en el sistema de emulaci\u00f3n y mejoras en la conversi\u00f3n de datos de algunos modelos de calibradores. Otro cambio es el aumento de la zona de medici\u00f3n necesaria dado el di\u00e1metro del Discus<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/basiccolor\/basICColor_DISCUS.php\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"calibrador discus\" src=\"http:\/\/www.microgamma.com\/basiccolor\/i\/productimage-DISCUSfrei.png\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"colonavigator\" src=\"http:\/\/www.microgamma.com\/software\/CN_64\/cn_abril_2013_01.png\" width=\"573\" height=\"380\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"colornavigator\" src=\"http:\/\/www.microgamma.com\/software\/CN_64\/cn_abril_2013_03.png\" width=\"535\" height=\"588\" \/><\/p>\n<p>http:\/\/www.eizo.com\/global\/support\/db\/files\/software\/software\/graphics\/colornavigator\/CN642.zip<\/p>\n<p>http:\/\/www.eizo.com\/global\/support\/db\/files\/software\/software\/graphics\/colornavigator\/ColorNavigator642.dmg<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se ha producido una actualizaci\u00f3n del software ColorNavigator 6.4.2.11 que es importante aplicar. A parte de cambios menores como es la compatibilidad de nuevos monitores hay que destacar la compatibilidad del calibrador Basiccolor Discus Se han realizado cambios en el sistema de emulaci\u00f3n y mejoras en la conversi\u00f3n de datos de algunos modelos de calibradores. [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[8,364,392,10],"tags":[],"class_list":["post-4151","post","type-post","status-publish","format-standard","hentry","category-calibradores-para-monitor","category-datacolor-calibradores-para-monitor","category-calibrarelmonitor","category-xrite"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=4151"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4151\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=4151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=4151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=4151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}