{"id":4259,"date":"2013-05-24T10:06:58","date_gmt":"2013-05-24T08:06:58","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=4259"},"modified":"2013-05-24T10:52:31","modified_gmt":"2013-05-24T08:52:31","slug":"visibledust-sensor-clean","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2013\/05\/visibledust-sensor-clean\/","title":{"rendered":"VisibleDust Sensor Clean"},"content":{"rendered":"<p><strong>Sensor Clean, liquido para la limpieza del sensor<\/strong><\/p>\n<p>El Sensor Clean tiene excelentes caracter\u00edsticas que lo hacen una elecci\u00f3n ideal para limpiar el sensor. Es el indicado para manchas de agua fruto de la condensaci\u00f3n y polvo ligero, proporciona una protecci\u00f3n antiest\u00e1tica para evitar que se adhiera de nuevo el polvo. Debe combinarse con los Sensor Swab MDX-100 de color verde.<\/p>\n<p>Todos de nuestras soluciones son seguros en todo tipo de sensores<br \/>\nLos l\u00edquidos de <strong>VisibleDust<\/strong> (el Sensor Clean, VDust Plus y Smear Away) utilizados en tos sensor Swab de <strong>VisibleDust<\/strong> son seguros y eficaces en todas las c\u00e1maras incluyendo: las \u00faltimas Canon como la 400D, 40D, 1D MKIII, y 1Ds MKIII, y las m\u00e1s nuevas de Nikon D300 y D3 y Alpha Sony 700<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/visible_dust\/liquido_sensor_clean.php\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" alt=\"visibledust iberia\" src=\"http:\/\/www.microgamma.com\/visible_dust\/sensor_clean\/Sensor_Clean_500X500.jpg\" width=\"277\" height=\"277\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/visible_dust\/liquido_sensor_clean.php\">http:\/\/www.microgamma.com\/visible_dust\/liquido_sensor_clean.php<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sensor Clean, liquido para la limpieza del sensor El Sensor Clean tiene excelentes caracter\u00edsticas que lo hacen una elecci\u00f3n ideal para limpiar el sensor. Es el indicado para manchas de agua fruto de la condensaci\u00f3n y polvo ligero, proporciona una protecci\u00f3n antiest\u00e1tica para evitar que se adhiera de nuevo el polvo. Debe combinarse con los [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[1135],"tags":[1138,996,585,1136,1139,1137],"class_list":["post-4259","post","type-post","status-publish","format-standard","hentry","category-visibledust-limpieza-sensor-y-camara","tag-sensorclean","tag-visible-dust-espana","tag-visibledust","tag-visibledust-espana","tag-visibledust-iberia","tag-visibledust-portugal"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=4259"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/4259\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=4259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=4259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=4259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}