{"id":6205,"date":"2015-03-06T15:09:34","date_gmt":"2015-03-06T13:09:34","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=6205"},"modified":"2020-02-05T01:02:11","modified_gmt":"2020-02-04T23:02:11","slug":"nuevo-tripode-c2682tv2","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2015\/03\/nuevo-tripode-c2682tv2\/","title":{"rendered":"Nuevo tr\u00edpode C2682TV2"},"content":{"rendered":"<p><a href=\"http:\/\/www.microgamma.com\/benro\/benro_dinamic.php?CODI=C2682TV2\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"http:\/\/www.microgamma.com\/600\/C2682TV2.jpg\" alt=\"benro c2682tv2\" width=\"401\" height=\"401\" \/><\/a><\/p>\n<p>El tr\u00edpode mas demandado por los amantes de la fotograf\u00eda de paisaje<\/p>\n<ul>\n<li>ligero, fabricado con fibra de carbono<\/li>\n<li>Robusto, cuatro tramos para minimizar las vibraciones del tr\u00edpode<\/li>\n<li>Rotula de alta resistencia, soporta hasta 25 Kg<\/li>\n<\/ul>\n<p><span class=\"normal_instop\">Los Travel Angel de Benro son famosos por ocupar el m\u00ednimo espaci\u00f3 posible y ser extremadamente ligeros, lo que les convierte en un tr\u00edpode ideal para viajes. Los tr\u00edpodes <a href=\"http:\/\/www.microgamma.com\/benro\/travel_angel_series_ii.php\">Travel Angel II Multifuncional<\/a> son un 3 en 1.<\/span><\/p>\n<p>La serie 80 se diferencia por tener 4 tramos en lugar de los 5 de la serie 90. Cada sistema tiene sus pros y sus contras, a menos tramos mayor estabilidad y robustez. Con mas tramos menor tama\u00f1o. Podr\u00e1 elegir seg\u00fan las aplicaciones que deba realizar con el. En general los de la serie 80 de este tipo los debemos considerar como tr\u00edpodes con un peso soportado extremos de 14 kg para el 1682 y de 18 Kg para el 2682.<\/p>\n<p>a partir de un tr\u00edpode con la r\u00f3tula V1 o V2, seg\u00fan el modelo. Lo podemos acabar convirtiendo en un excepcional monopie con r\u00f3tula en tan solo en tres sencillos movimientos y en menos de 10 seg. Tambi\u00e9n se convierte en un bast\u00f3n de monta\u00f1a.<\/p>\n<p>Tr\u00edpode, monopi\u00e9 y bast\u00f3n de monta\u00f1a todo en uno.<\/p>\n<p><a href=\"http:\/\/www.microgamma.com\/benro\/benro_dinamic.php?CODI=C2682TV2\">http:\/\/www.microgamma.com\/benro\/benro_dinamic.php?CODI=C2682TV2<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El tr\u00edpode mas demandado por los amantes de la fotograf\u00eda de paisaje ligero, fabricado con fibra de carbono Robusto, cuatro tramos para minimizar las vibraciones del tr\u00edpode Rotula de alta resistencia, soporta hasta 25 Kg Los Travel Angel de Benro son famosos por ocupar el m\u00ednimo espaci\u00f3 posible y ser extremadamente ligeros, lo que les [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[808,1,392],"tags":[15011,2043,2375,15902,15904,17574,15903,15905,2573,2374,14926,15908,15907,2574,2347,2376,13403,2373,20697,2377,15909,2348,15906,19890,2349,2564],"class_list":["post-6205","post","type-post","status-publish","format-standard","hentry","category-benro","category-general","category-calibrarelmonitor","tag-bemro-travel-angel-2682","tag-benro-2682","tag-benro-a2682tv2","tag-benro-c-269-m8","tag-benro-c-269-m8-en-espanol","tag-benro-c-2691","tag-benro-c-269m8","tag-benro-c-269m8-precio","tag-benro-c2682-medidas","tag-benro-c2682tv2","tag-benro-c269-m8","tag-benro-serie-angel","tag-benron-tripode","tag-c2682-medidas","tag-c2682tv2","tag-c2682tv2-benro","tag-ct2682c-benro","tag-donde-comprar-benro-c2682tv2","tag-opiniones-sobre-tripode-benro-c2682t","tag-precio-benro-c2682tb1","tag-productos-benro","tag-tripode-benro-2682","tag-tripode-benro-arca-swiss","tag-tripode-benro-travel-angel-ii-series-carbono-c2682tv2","tag-tripode-de-carbono","tag-tripodes-benro-opiniones"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=6205"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/6205\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=6205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=6205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=6205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}