{"id":9273,"date":"2018-10-04T11:30:12","date_gmt":"2018-10-04T09:30:12","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=9273"},"modified":"2020-01-22T12:00:28","modified_gmt":"2020-01-22T10:00:28","slug":"zeiss-batis-2-8-135","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2018\/10\/zeiss-batis-2-8-135\/","title":{"rendered":"ZEISS BATIS 2.8\/135"},"content":{"rendered":"<p><strong>ZEISS Batis 2.8\/135, teleobjetivo compacto con autofoco para montura Sony E, ideal para retrato.<\/strong><\/p>\n<p><strong>El nuevo objetivo ZEISS Batis 2.8\/135 es el primer AF con distancia focal 135 mm para c\u00e1maras mirrorless full-frame de Sony.<\/strong><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.microgamma.com\/zeiss\/zeiss.php?CODI=2136-695\"><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/zeiss\/batis\/zeiss-batis-28135-product-02.jpg\" \/><\/a><\/p>\n<p>Los fans de las c\u00e1maras mirrorless full-frame de Sony tienen un motivo para sonre\u00edr: ZEISS aumenta la familia de objetivos Batis con un teleobjetivo. El nuevo ZEISS Batis 2.8\/135 es el primer objetivo AF de distancia focal 135 mm para c\u00e1maras del sistema Sony Alpha 7 con montura E. Como todos los objetivos de la gama Batis de ZEISS, est\u00e1 equipado con un autofoco r\u00e1pido y preciso. Para evitar las vibraciones, tan frecuentes con teleobjetivos, se ha incorporado tambi\u00e9n en el dise\u00f1o un estabilizador \u00f3ptico de imagen. El ZEISS Batis 2.8\/135 demuestra particularmente su val\u00eda en fotograf\u00eda de retrato: \u201cLa distancia focal de teleobjetivo permite destacar bien al sujeto sobre un fondo borroso\u201d, die Michael Pollman, Product Manger de ZEISS. \u201cEl bokeh funciona muy bien, y el dise\u00f1o \u00f3ptico \u2013un Apo Sonnar- asegura im\u00e1genes sobresalientes siempre\u201d. El nuevo ZEISS Batis tambi\u00e9n puede ser una gran opci\u00f3n para fotograf\u00eda social y de eventos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/zeiss\/batis\/zeiss-batis-28135-lens-slider-02.jpg\" \/><\/p>\n<p><strong>\u201cCompacto, ligero, de primera calidad\u201d<\/strong><\/p>\n<p>\u201cLa ventaja de las c\u00e1maras Sony mirrorless full-frame es que, a pesar de su tama\u00f1o compacto, ofrecen una calidad de imagen excepcional\u201d, dice Pollman. ZEISS ha continuado llevando el dise\u00f1o del ZEISS Batis 2.8\/135 hacia las necesidades de los fot\u00f3grafos de Sony. \u201cEra importante construir un objetivo comparativamente manejable, a pesar de tener una longitud focal bastante larga. Tomamos la decisi\u00f3n consciente de conseguir el equilibro entre el tama\u00f1o compacto, el peso y la intensidad de luz\u201d.<\/p>\n<p><strong>Display OLED para visualizar la profundidad de enfoque<\/strong><strong>\u00a0<\/strong><\/p>\n<p>Como todos los objetivos Batis, este nuevo miembro de la familia cuenta con un display OLED que permite una visualizaci\u00f3n precisa de la profundidad de campo. Esto asegura que la imagen est\u00e1 enfocada en todas partes. El cuerpo met\u00e1lico otorga al objetivo robustez y durabilidad. ZEISS asegura que su protecci\u00f3n contra polvo y suciedad convierten las tomas en condiciones de mal tiempo en un paseo por el parque.<\/p>\n<p>La calidad de imagen no deja nada que desear: \u201cHemos puesto mucho esfuerzo en el dise\u00f1o \u00f3ptico y en la correcci\u00f3n de nuestras lentes\u201d, dice Pollman. \u201cPor ejemplo, estamos experimentando con tipos de cristal especiales para corregir tantos tipos de errores de imagen como sea posible. As\u00ed hemos sido capaces de asegurar la correcci\u00f3n de la aberraci\u00f3n crom\u00e1tica en el ZEISS Batis 2.8\/135, de tal forma que pr\u00e1cticamente no tengamos errores de imagen\u201d. En este objetivo se ha construido con 14 lentes en 11 grupos.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/zeiss\/batis\/zeiss-batis-28135-application-01.jpg\" \/><\/p>\n<p><strong>Precio y disponibilidad<\/strong><\/p>\n<p>El\u00a0<a title=\"Zeiss Batis 2.8\/135\" href=\"http:\/\/www.fototecnica.com\/zeiss-objetivo-batis-135-2-8-e-sony.html\" target=\"_blank\" rel=\"noopener noreferrer\">ZEISS Batis 2.8\/135<\/a>\u00a0estar\u00e1 disponible en tiendas especialistas a principios de mayo de 2017, a un precio de 1.999 \u20ac IVA incluido.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Especificaciones t\u00e9cnicas ZEISS Batis 2.8\/135<\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>Distancia focal:<\/strong>135 mm<\/p>\n<p><strong>Rango de apertura:\u00a0<\/strong>f\/2.8 \u2013 f\/22<\/p>\n<p><strong>Elementos \/ grupos:\u00a0<\/strong>14 \/ 11<\/p>\n<p><strong>Estabilizaci\u00f3n \u00f3ptica de imagen:\u00a0<\/strong>S\u00ed<\/p>\n<p><strong>Rango de enfoque:\u00a0<\/strong>0,87 m (2,86 ft) &#8211; \u221e<\/p>\n<p><strong>Distancia de Trabajo:\u00a0<\/strong>\u00a00,74 m (2,4 ft) &#8211; \u221e<\/p>\n<p><strong>\u00c1ngulo de visi\u00f3n (diag. \/ horiz. \/ vert.):\u00a0<\/strong>\u00a018\u00ba \/ 15\u00ba \/ 10\u00ba<\/p>\n<p><strong>Di\u00e1metro del campo de imagen:\u00a0<\/strong>43,3 mm (1,7\u201d)<\/p>\n<p><strong>Distancia focal desde el borde:\u00a0<\/strong>18,0 mm (0,71\u201d)<\/p>\n<p><strong>Cobertura en rango corto (MOD)*: \u00a0<\/strong>\u00a0125 x 185 mm (4,9 x 7,3\u201d)<\/p>\n<p><strong>Ratio de imagen en MOD:\u00a0<\/strong>1:5:3<\/p>\n<p><strong>Di\u00e1metro del filtro:\u00a0<\/strong>M67 x 0,75<\/p>\n<p><strong>Posici\u00f3n entrada pupila (detr\u00e1s del plano de imagen):\u00a0<\/strong>6,9 mm (0,27\u201d)<\/p>\n<p><strong>\u00c1ngulo de rotaci\u00f3n del anillo de enfoque (inf \u2013 MOD):<\/strong>\u00a0 Enfoque no acoplado mec\u00e1nicamente. El \u00e1ngulo de rotaci\u00f3n depende de la velocidad de rotaci\u00f3n.<\/p>\n<p><strong>Di\u00e1metro m\u00e1ximo (con parasol):\u00a0<\/strong>98 mm (3,9\u201d)<\/p>\n<p><strong>Di\u00e1metro del anillo de enfoque:\u00a0<\/strong>81 mm (3,2\u201d)<\/p>\n<p><strong>Longitud (sin tapas):<\/strong>\u00a0120 mm (4,7\u201d)<\/p>\n<p><strong>Longitud (con tapas):\u00a0<\/strong>\u00a0133 mm (5,2\u201d)<\/p>\n<p><strong>Peso (sin tapas):\u00a0<\/strong>614 g (1,35 lbs)<\/p>\n<p>* Basado en formato 24&#215;36 mm.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/zeiss\/batis\/zeiss-batis-28135-product-05.jpg\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZEISS Batis 2.8\/135, teleobjetivo compacto con autofoco para montura Sony E, ideal para retrato. El nuevo objetivo ZEISS Batis 2.8\/135 es el primer AF con distancia focal 135 mm para c\u00e1maras mirrorless full-frame de Sony.\u00a0 &nbsp; Los fans de las c\u00e1maras mirrorless full-frame de Sony tienen un motivo para sonre\u00edr: ZEISS aumenta la familia de [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[355],"tags":[6424,13281,12543,13282,6626,13001,5629,7267,6985,13310,17223,6604,6605,6421,13311,6423,6422,13000,6606,20310],"class_list":["post-9273","post","type-post","status-publish","format-standard","hentry","category-zeiss","tag-a7-lll-con-zeiss-batis-135mm-f-2-8","tag-buy-sony-batis-135mm-without-vat","tag-como-funciona-la-reticula-iluminada-60-de-los-zeiss","tag-cual-es-el-mejor-objetivo-135mm","tag-cuando-salio-el-zeiss-batis-135-mmf2-8","tag-objetivo-16-70-montura-e-para-sony-a7lll","tag-para-poner-foto-en-pantalla-principal","tag-que-tienen-de-especial-los-objetivos-zeiss","tag-rrebala-pero-pastoralemar-esp-batis","tag-zeis-batis-cashback","tag-zeiss-batis-135-dimensiones","tag-zeiss-batis-135-f2-8","tag-zeiss-batis-135-f2-8-analisis-en-espanol","tag-zeiss-batis-135mm-2-8-y-a-7-lll-compatibilidad","tag-zeiss-batis-135mm-f-2-8","tag-zeiss-batis-2-8-135","tag-zeiss-batis-2-8-135-precio","tag-zeiss-batis-nikon","tag-zeiss-betis-135-mm-f2-8-y-la-canon-r","tag-zeiss-sony-e"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=9273"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9273\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=9273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=9273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=9273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}