{"id":9591,"date":"2019-01-21T19:10:10","date_gmt":"2019-01-21T17:10:10","guid":{"rendered":"http:\/\/www.microgamma.es\/blog\/?p=9591"},"modified":"2020-01-31T00:58:34","modified_gmt":"2020-01-30T22:58:34","slug":"laowa-10-18mm-f-4-5-5-6-fe-zoom","status":"publish","type":"post","link":"https:\/\/www.microgamma.es\/blog\/index.php\/2019\/01\/laowa-10-18mm-f-4-5-5-6-fe-zoom\/","title":{"rendered":"Laowa 10-18mm f\/4.5-5.6 FE Zoom"},"content":{"rendered":"<p><a href=\"https:\/\/www.microgamma.com\/laowa\/laowa.php?CODI=VE1018SFE\"><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/laowa\/10-18\/VE1018SFE-02.jpg\" \/><\/a><\/p>\n<a class=\"maxbutton-1 maxbutton maxbutton-comprar-ahora\" target=\"_blank\" rel=\"noopener\" href=\"https:\/\/www.microgamma.com\/shop.php?REF=VE1018SFE\"><span class='mb-text'>Comprar Ahora<\/span><\/a>\n<p>&nbsp;<\/p>\n<p>Este objetivo <a href=\"https:\/\/www.microgamma.com\/laowa\/laowa.php?CODI=VE1018SFE\">Laowa 10-18<\/a> es actualmente el zoom con m\u00e1s amplitud disponible para las c\u00e1maras con montura E full frame para Sony. Dise\u00f1ados principalmente para fotograf\u00eda de viajes, se ha logrado comprimir el tama\u00f1o al m\u00e1s peque\u00f1o de su clase, con menos de 9.1 cm de largo y solo 496 gr. El \u00e1ngulo de visi\u00f3n de 102 \u00b0 (18 mm) a 130 \u00b0 (10 mm) proporciona flexibilidad a los fot\u00f3grafos para componer fotos de paisajes o arquitectura con facilidad. El sistema de apertura se ha dise\u00f1ado cuidadosamente para reproducir de la mejor posible los reflejos producidos por la luz incidente, se puede decir que es la mejor de los objetivos ultra gran angular.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/laowa\/10-18\/Lense-Comparison-1.jpg\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/laowa\/10-18\/GIF.gif\" \/><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/laowa\/10-18\/1018-20180920-2-1-1200x808.jpg\" \/><\/p>\n<p>\u00a9 Gong Xiao Jian<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/laowa\/10-18\/44846167_111765333088626_7417770620294791168_n-1200x801.jpg\" \/><\/p>\n<p>\u00a9 Albert Dros<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.microgamma.com\/laowa\/10-18\/DSC09754-Pano-2-1-1-1200x863.jpg\" \/><\/p>\n<p>\u00a9 Mi Ge<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Este objetivo Laowa 10-18 es actualmente el zoom con m\u00e1s amplitud disponible para las c\u00e1maras con montura E full frame para Sony. Dise\u00f1ados principalmente para fotograf\u00eda de viajes, se ha logrado comprimir el tama\u00f1o al m\u00e1s peque\u00f1o de su clase, con menos de 9.1 cm de largo y solo 496 gr. El \u00e1ngulo de [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"site-container-style":"default","site-container-layout":"default","site-sidebar-layout":"default","disable-article-header":"default","disable-site-header":"default","disable-site-footer":"default","disable-content-area-spacing":"default","footnotes":""},"categories":[1],"tags":[17547,10562,7437,10808,10602,7438,13090,10561,10560],"class_list":["post-9591","post","type-post","status-publish","format-standard","hentry","category-general","tag-10-18mm","tag-accesorios-de-decorar-para-fotografias","tag-laowa-10-18","tag-laowa-10-18-fe-review","tag-laowa-10-18-review","tag-laowa-10-18mm","tag-laowa-10-18mm-f4-5-5-6-opiniones","tag-opinion-laowa-10-18","tag-opiniones-laowa-10-18"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=9591"}],"version-history":[{"count":0,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/posts\/9591\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=9591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=9591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.microgamma.es\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=9591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}